{"id":666,"date":"2023-12-01T10:02:35","date_gmt":"2023-12-01T13:02:35","guid":{"rendered":"https:\/\/www.cnbf.org.br\/?p=666"},"modified":"2023-12-01T10:03:09","modified_gmt":"2023-12-01T13:03:09","slug":"credenciamento-de-imprensa-para-o-30-campeonato-nacional","status":"publish","type":"post","link":"https:\/\/www.cnbf.org.br\/index.php\/2023\/12\/01\/credenciamento-de-imprensa-para-o-30-campeonato-nacional\/","title":{"rendered":"CREDENCIAMENTO DE IMPRENSA PARA O 30\u00ba CAMPEONATO NACIONAL DE BANDAS E FANFARRAS"},"content":{"rendered":"<p style=\"text-align: justify;\">No XXX Campeonato Nacional de Bandas e Fanfarras, o preenchimento da ficha de imprensa \u00e9 de extrema import\u00e2ncia para os profissionais que desejam ter acesso \u00e0s \u00e1reas de apresenta\u00e7\u00f5es das bandas. Sem esse credenciamento, o acesso a essas \u00e1reas fica restrito, impedindo o profissional de realizar seu trabalho de forma adequada.<\/p>\n<p style=\"text-align: justify;\">A ficha de imprensa \u00e9 um documento que permite a organiza\u00e7\u00e3o do evento identificar e controlar os profissionais da imprensa que estar\u00e3o presentes no campeonato. Ela cont\u00e9m informa\u00e7\u00f5es como nome, ve\u00edculo de comunica\u00e7\u00e3o, fun\u00e7\u00e3o e contato do profissional. Ao preencher corretamente essa ficha, o jornalista ou fot\u00f3grafo garante sua credencial de imprensa, que \u00e9 essencial para ter acesso \u00e0s \u00e1reas restritas.<\/p>\n<p style=\"text-align: justify;\">Al\u00e9m de facilitar o controle de acesso, o preenchimento da ficha de imprensa tamb\u00e9m \u00e9 importante para a organiza\u00e7\u00e3o do evento, pois permite que sejam enviadas informa\u00e7\u00f5es relevantes sobre o campeonato, como hor\u00e1rios das apresenta\u00e7\u00f5es e outras atividades exclusivas para a imprensa. Dessa forma, o profissional fica atualizado e pode planejar sua cobertura de forma mais eficiente.<\/p>\n<p style=\"text-align: justify;\">Portanto, \u00e9 fundamental que todos os profissionais interessados em cobrir o XXX Campeonato Nacional de Bandas e Fanfarras preencham corretamente a ficha de imprensa. Essa \u00e9 a garantia de acesso \u00e0s \u00e1reas de apresenta\u00e7\u00f5es das bandas e de recebimento das informa\u00e7\u00f5es necess\u00e1rias para uma cobertura completa e de qualidade.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/forms.gle\/X5acoCas3WNdosjMA\">Acessem o formul\u00e1rio aqui!<\/a><\/p>\n<p style=\"text-align: justify;\">Informa\u00e7\u00f5es complementares e solicita\u00e7\u00f5es podem ser feitas pelo e-mail <a href=\"mailto:imprensa@cnbf.org.br\">imprensa@cnbf.org.br<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No XXX Campeonato Nacional de Bandas e Fanfarras, o preenchimento da ficha de imprensa \u00e9 de extrema import\u00e2ncia para os profissionais que desejam ter acesso \u00e0s \u00e1reas de apresenta\u00e7\u00f5es das bandas. Sem esse credenciamento, o acesso a essas \u00e1reas fica restrito, impedindo o profissional de realizar seu trabalho de forma adequada. A ficha de imprensa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[60],"tags":[35,65,36,63,55,61,62,64],"class_list":["post-666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional2023","tag-bandas","tag-estadio-olimpico","tag-fanfarras","tag-fotografos","tag-goiania","tag-imprensa","tag-midia","tag-nacional23"],"wpmagazine_modules_lite_featured_media_urls":{"thumbnail":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st-150x150.png",150,150,true],"cvmm-medium":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png",300,300,false],"cvmm-medium-plus":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png",207,207,false],"cvmm-portrait":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png",400,400,false],"cvmm-medium-square":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png",600,600,false],"cvmm-large":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png",1024,1024,false],"cvmm-small":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png",95,95,false],"full":["https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png",1080,1080,false]},"categories_names":{"60":{"name":"NACIONAL 2023","link":"https:\/\/www.cnbf.org.br\/index.php\/category\/nacional2023\/"}},"tags_names":{"35":{"name":"bandas","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/bandas\/"},"65":{"name":"estadio olimpico","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/estadio-olimpico\/"},"36":{"name":"fanfarras","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/fanfarras\/"},"63":{"name":"fotografos","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/fotografos\/"},"55":{"name":"goiania","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/goiania\/"},"61":{"name":"imprensa","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/imprensa\/"},"62":{"name":"midia","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/midia\/"},"64":{"name":"nacional23","link":"https:\/\/www.cnbf.org.br\/index.php\/tag\/nacional23\/"}},"comments_number":"0","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.cnbf.org.br\/wp-content\/uploads\/2023\/12\/CREDENCIAMENTO-DE-MIDIA-st.png","_links":{"self":[{"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/posts\/666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=666"}],"version-history":[{"count":0,"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/posts\/666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/media\/667"}],"wp:attachment":[{"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cnbf.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}